{"id":23470,"date":"2026-05-13T18:31:29","date_gmt":"2026-05-13T14:01:29","guid":{"rendered":"https:\/\/wikishop.co\/mag\/?p=23470"},"modified":"2026-05-13T18:31:29","modified_gmt":"2026-05-13T14:01:29","slug":"geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina","status":"publish","type":"post","link":"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/","title":{"rendered":"\u0648\u0631\u0648\u062f \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 L7 \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u0634\u0631\u06a9\u062a \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u0628\u0631\u0646\u0627\u0645\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u062f\u0648 \u0645\u062d\u0635\u0648\u0644 \u062c\u062f\u06cc\u062f \u0627\u0632 \u0628\u0631\u0646\u062f \u062c\u06cc\u0644\u06cc \u0634\u0627\u0645\u0644 \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 \u06af\u0644\u06a9\u0633\u06cc L7 \u0631\u0627 \u062f\u0631 \u062f\u0633\u062a\u0648\u0631 \u06a9\u0627\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0632\u0645\u0627\u0646 \u0628\u0627 \u0627\u0646\u062a\u0634\u0627\u0631 \u06a9\u0627\u062a\u0627\u0644\u0648\u06af \u0627\u06cc\u0646 \u062f\u0648 \u062e\u0648\u062f\u0631\u0648\u060c \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062a\u0627\u0632\u0647\u200c\u0627\u06cc \u0627\u0632 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u062c\u0648\u0632\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0646\u0633\u062e\u0647 \u0647\u06cc\u0628\u0631\u06cc\u062f\u06cc EM-i \u06a9\u0631\u0627\u0633\u200c\u0627\u0648\u0648\u0631 L7 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f\u0647 \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0639\u0631\u0636\u0647 \u0627\u06cc\u0646 \u0645\u062f\u0644 \u062f\u0631 \u0627\u0648\u0644\u0648\u06cc\u062a \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a. \u0647\u0631 \u062f\u0648 \u062e\u0648\u062f\u0631\u0648 \u0628\u0627 \u0642\u0648\u0627\u06cc \u0645\u062d\u0631\u06a9\u0647 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f \u0648 \u062a\u0648\u0627\u0646 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u06f3\u06f8\u06f5 \u0627\u0633\u0628 \u0628\u062e\u0627\u0631 \u0648\u0627\u0631\u062f \u0628\u0627\u0632\u0627\u0631 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f.<\/span><\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u062c\u062f\u0648\u0644 \u0645\u062d\u062a\u0648\u0627<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%A2%D8%BA%D8%A7%D8%B2_%D9%85%D8%B3%DB%8C%D8%B1_%D8%AC%D8%AF%DB%8C%D8%AF_%D8%B3%D8%B1%D9%88%D8%B4_%D9%85%D8%A8%DB%8C%D9%86%D8%A7_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%D8%AE%D9%88%D8%AF%D8%B1%D9%88%D9%87%D8%A7%DB%8C_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA%DB%8C\" >\u0622\u063a\u0627\u0632 \u0645\u0633\u06cc\u0631 \u062c\u062f\u06cc\u062f \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u062e\u0648\u062f\u0631\u0648\u0647\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%AA%D8%BA%DB%8C%DB%8C%D8%B1_%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D8%A7%D8%B2_%D9%85%DB%8C%D9%BE%D9%84_%D8%A8%D9%87_%D8%AE%D8%A7%D9%86%D9%88%D8%A7%D8%AF%D9%87_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_%D8%AC%DB%8C%D9%84%DB%8C\" >\u062a\u063a\u06cc\u06cc\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0627\u0632 \u0645\u06cc\u067e\u0644 \u0628\u0647 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u06af\u0644\u06a9\u0633\u06cc \u062c\u06cc\u0644\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87_%D8%A7%D9%88%D9%84%DB%8C%D9%87_%D9%88_%D9%88%D8%B6%D8%B9%DB%8C%D8%AA_%D9%81%D8%B9%D9%84%DB%8C_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA\" >\u0628\u0631\u0646\u0627\u0645\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0648 \u0648\u0636\u0639\u06cc\u062a \u0641\u0639\u0644\u06cc \u0648\u0627\u0631\u062f\u0627\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%AF%D8%B1%DB%8C%D8%A7%D9%81%D8%AA_%D9%85%D8%AC%D9%88%D8%B2_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%DB%8C%D9%84%DB%8C_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_L7_%D9%86%D8%B3%D8%AE%D9%87_EM-i\" >\u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u062c\u0648\u0632 \u0628\u0631\u0627\u06cc \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L7 \u0646\u0633\u062e\u0647 EM-i<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%AE%D9%88%D8%AF%D8%B1%D9%88%D9%87%D8%A7%DB%8C_%D8%A2%D9%85%D8%A7%D8%AF%D9%87_%D8%B9%D8%B1%D8%B6%D9%87\" >\u062e\u0648\u062f\u0631\u0648\u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 \u0639\u0631\u0636\u0647<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%B3%D8%A7%D8%A8%D9%82%D9%87_%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87_%D8%B9%D8%B1%D8%B6%D9%87_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_L6_%D9%88_L7_%D8%AF%D8%B1_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86\" >\u0633\u0627\u0628\u0642\u0647 \u0628\u0631\u0646\u0627\u0645\u0647 \u0639\u0631\u0636\u0647 \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 L7 \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D9%88%D8%B6%D8%B9%DB%8C%D8%AA_%D9%82%D8%A8%D9%84%DB%8C_%D8%B9%D8%B1%D8%B6%D9%87_%D8%A7%DB%8C%D9%86_%D9%85%D8%AD%D8%B5%D9%88%D9%84%D8%A7%D8%AA\" >\u0648\u0636\u0639\u06cc\u062a \u0642\u0628\u0644\u06cc \u0639\u0631\u0636\u0647 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D9%85%D8%B4%D8%AE%D8%B5%D8%A7%D8%AA_%D9%81%D9%86%DB%8C_%D8%AC%DB%8C%D9%84%DB%8C_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_L6_%D9%88_L7\" >\u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 L7<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D9%82%D9%88%D8%A7%DB%8C_%D9%85%D8%AD%D8%B1%DA%A9%D9%87_%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86_%D9%87%DB%8C%D8%A8%D8%B1%DB%8C%D8%AF_%D8%A8%D8%A7_%D8%AA%D9%88%D8%A7%D9%86_%DB%B3%DB%B8%DB%B5_%D8%A7%D8%B3%D8%A8_%D8%A8%D8%AE%D8%A7%D8%B1\" >\u0642\u0648\u0627\u06cc \u0645\u062d\u0631\u06a9\u0647 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f \u0628\u0627 \u062a\u0648\u0627\u0646 \u06f3\u06f8\u06f5 \u0627\u0633\u0628 \u0628\u062e\u0627\u0631<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D9%85%D8%B4%D8%AE%D8%B5%D8%A7%D8%AA_%D9%BE%DB%8C%D8%B4%D8%B1%D8%A7%D9%86%D9%87\" >\u0645\u0634\u062e\u0635\u0627\u062a \u067e\u06cc\u0634\u0631\u0627\u0646\u0647<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%B8%D8%B1%D9%81%DB%8C%D8%AA_%D8%A8%D8%A7%D8%AA%D8%B1%DB%8C_%D9%88_%D9%85%DB%8C%D8%B2%D8%A7%D9%86_%D9%BE%DB%8C%D9%85%D8%A7%DB%8C%D8%B4\" >\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u062a\u0631\u06cc \u0648 \u0645\u06cc\u0632\u0627\u0646 \u067e\u06cc\u0645\u0627\u06cc\u0634<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%A8%D8%A7%D8%AA%D8%B1%DB%8C_%D9%88_%D8%A8%D8%B1%D8%AF_%D8%AD%D8%B1%DA%A9%D8%AA%DB%8C\" >\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u0627\u062a\u0631\u06cc \u0648 \u0628\u0631\u062f \u062d\u0631\u06a9\u062a\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D9%BE%DB%8C%D9%85%D8%A7%DB%8C%D8%B4_%D8%AA%D9%85%D8%A7%D9%85_%D8%A8%D8%B1%D9%82%DB%8C_%D9%88_%D8%B4%D8%AA%D8%A7%D8%A8_%D8%AE%D9%88%D8%AF%D8%B1%D9%88%D9%87%D8%A7\" >\u067e\u06cc\u0645\u0627\u06cc\u0634 \u062a\u0645\u0627\u0645 \u0628\u0631\u0642\u06cc \u0648 \u0634\u062a\u0627\u0628 \u062e\u0648\u062f\u0631\u0648\u0647\u0627<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/wikishop.co\/mag\/geely-galaxy-l6-and-l7-enter-the-iranian-market-with-soroush-mobina\/#%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D8%AD%D8%B1%DA%A9%D8%AA%DB%8C\" >\u0639\u0645\u0644\u06a9\u0631\u062f \u062d\u0631\u06a9\u062a\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A2%D8%BA%D8%A7%D8%B2_%D9%85%D8%B3%DB%8C%D8%B1_%D8%AC%D8%AF%DB%8C%D8%AF_%D8%B3%D8%B1%D9%88%D8%B4_%D9%85%D8%A8%DB%8C%D9%86%D8%A7_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%D8%AE%D9%88%D8%AF%D8%B1%D9%88%D9%87%D8%A7%DB%8C_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA%DB%8C\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0622\u063a\u0627\u0632 \u0645\u0633\u06cc\u0631 \u062c\u062f\u06cc\u062f \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u062e\u0648\u062f\u0631\u0648\u0647\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a\u06cc<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%BA%DB%8C%DB%8C%D8%B1_%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D8%A7%D8%B2_%D9%85%DB%8C%D9%BE%D9%84_%D8%A8%D9%87_%D8%AE%D8%A7%D9%86%D9%88%D8%A7%D8%AF%D9%87_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_%D8%AC%DB%8C%D9%84%DB%8C\"><\/span><span style=\"font-size: 14pt;\"><strong>\u062a\u063a\u06cc\u06cc\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0627\u0632 \u0645\u06cc\u067e\u0644 \u0628\u0647 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u06af\u0644\u06a9\u0633\u06cc \u062c\u06cc\u0644\u06cc<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u06a9\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u067e\u0627\u06cc\u06cc\u0632 \u06f1\u06f4\u06f0\u06f3 \u0622\u063a\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0628\u0648\u062f\u060c \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0646\u0627\u0645\u0647 \u0639\u0631\u0636\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u06cc \u0627\u0632 \u0628\u0631\u0646\u062f\u0647\u0627\u06cc MAPLE \u0648 GAC \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0631\u062f. \u0628\u0627 \u0648\u062c\u0648\u062f \u0645\u0639\u0631\u0641\u06cc \u0627\u0648\u0644\u06cc\u0647 \u0645\u062f\u0644 MAPLE 60S\u060c \u062a\u0627\u06a9\u0646\u0648\u0646 \u0639\u0631\u0636\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062e\u0648\u062f\u0631\u0648 \u0627\u0646\u062c\u0627\u0645 \u0646\u0634\u062f\u0647 \u0648 \u0627\u06a9\u0646\u0648\u0646 \u0646\u0634\u0627\u0646\u0647\u200c\u0647\u0627 \u0627\u0632 \u062a\u063a\u06cc\u06cc\u0631 \u062a\u0645\u0631\u06a9\u0632 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0628\u0647 \u0633\u0645\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0633\u0631\u06cc \u06af\u0644\u06a9\u0633\u06cc \u062c\u06cc\u0644\u06cc \u062d\u06a9\u0627\u06cc\u062a \u062f\u0627\u0631\u062f. \u0627\u0646\u062a\u0634\u0627\u0631 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062c\u062f\u06cc\u062f \u0646\u06cc\u0632 \u0627\u06cc\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u0645\u0633\u06cc\u0631 \u0631\u0627 \u062a\u0623\u06cc\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87_%D8%A7%D9%88%D9%84%DB%8C%D9%87_%D9%88_%D9%88%D8%B6%D8%B9%DB%8C%D8%AA_%D9%81%D8%B9%D9%84%DB%8C_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0628\u0631\u0646\u0627\u0645\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0648 \u0648\u0636\u0639\u06cc\u062a \u0641\u0639\u0644\u06cc \u0648\u0627\u0631\u062f\u0627\u062a<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0628\u0631\u0646\u0627\u0645\u0647 \u0642\u0628\u0644\u06cc<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0648\u0636\u0639\u06cc\u062a \u0641\u0639\u0644\u06cc<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0648\u0627\u0631\u062f\u0627\u062a <\/strong><strong>MAPLE <\/strong><strong>60<\/strong><strong>S<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u0639\u0631\u0636\u0647 \u0627\u0646\u062c\u0627\u0645 \u0646\u0634\u062f\u0647<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0639\u0631\u0636\u0647 \u0628\u0631\u062e\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a <\/strong><strong>GAC<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u0628\u062f\u0648\u0646 \u0627\u0639\u0644\u0627\u0645 \u0632\u0645\u0627\u0646<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062a\u0645\u0631\u06a9\u0632 \u062c\u062f\u06cc\u062f<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 L7<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%DB%8C%D8%A7%D9%81%D8%AA_%D9%85%D8%AC%D9%88%D8%B2_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%DB%8C%D9%84%DB%8C_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_L7_%D9%86%D8%B3%D8%AE%D9%87_EM-i\"><\/span><span style=\"font-size: 14pt;\"><strong>\u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u062c\u0648\u0632 \u0628\u0631\u0627\u06cc \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>7 \u0646\u0633\u062e\u0647 <\/strong><strong>EM-i<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0646\u062a\u0634\u0631\u0634\u062f\u0647 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u0628\u0627 \u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc \u00ab\u0633\u0648\u0645\u0648 \u0645\u0648\u062a\u0648\u0631\u0632\u00bb \u0645\u0648\u0641\u0642 \u0628\u0647 \u062f\u0631\u06cc\u0627\u0641\u062a \u06af\u0648\u0627\u0647\u06cc \u0635\u062d\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u062a\u0623\u06cc\u06cc\u062f \u0646\u0648\u0639 \u0628\u0631\u0627\u06cc \u06a9\u0631\u0627\u0633\u200c\u0627\u0648\u0648\u0631 \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L7 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0645\u062c\u0648\u0632 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0646\u0633\u062e\u0647 EM-i \u0628\u0648\u062f\u0647 \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0642\u062f\u0645\u0647 \u0622\u063a\u0627\u0632 \u0641\u0631\u0622\u06cc\u0646\u062f \u0639\u0631\u0636\u0647 \u0631\u0633\u0645\u06cc \u0627\u06cc\u0646 \u062e\u0648\u062f\u0631\u0648 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627\u0634\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u06a9\u0627\u062a\u0627\u0644\u0648\u06af \u0631\u0633\u0645\u06cc L7 \u0648 \u0646\u0633\u062e\u0647 \u0633\u062f\u0627\u0646 L6 \u0646\u06cc\u0632 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%AF%D8%B1%D9%88%D9%87%D8%A7%DB%8C_%D8%A2%D9%85%D8%A7%D8%AF%D9%87_%D8%B9%D8%B1%D8%B6%D9%87\"><\/span><span style=\"font-size: 14pt;\"><strong>\u062e\u0648\u062f\u0631\u0648\u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 \u0639\u0631\u0636\u0647<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062e\u0648\u062f\u0631\u0648<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u06a9\u0644\u0627\u0633 \u0628\u062f\u0646\u0647<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0646\u0633\u062e\u0647<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>6<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u0633\u062f\u0627\u0646<\/span><\/td>\n<td><span style=\"font-size: 14pt;\">EM-i<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>7<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06a9\u0631\u0627\u0633\u200c\u0627\u0648\u0648\u0631<\/span><\/td>\n<td><span style=\"font-size: 14pt;\">EM-i<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B3%D8%A7%D8%A8%D9%82%D9%87_%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D9%87_%D8%B9%D8%B1%D8%B6%D9%87_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_L6_%D9%88_L7_%D8%AF%D8%B1_%D8%A7%DB%8C%D8%B1%D8%A7%D9%86\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0633\u0627\u0628\u0642\u0647 \u0628\u0631\u0646\u0627\u0645\u0647 \u0639\u0631\u0636\u0647 \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>6 \u0648 <\/strong><strong>L<\/strong><strong>7 \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u067e\u06cc\u0634 \u0627\u0632 \u0627\u06cc\u0646 \u0646\u06cc\u0632 \u0628\u0631\u0646\u0627\u0645\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0627\u06cc\u0646 \u062f\u0648 \u0645\u062d\u0635\u0648\u0644 \u062a\u0648\u0633\u0637 \u06a9\u0631\u0645\u0627\u0646 \u0645\u0648\u062a\u0648\u0631 \u0645\u0637\u0631\u062d \u0634\u062f\u0647 \u0628\u0648\u062f \u0648 \u062d\u062a\u06cc \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc\u06cc \u0627\u0632 \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u0631\u0627\u062d\u0644 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u062c\u0648\u0632 \u0648\u0627\u0631\u062f \u06a9\u0634\u0648\u0631 \u0634\u062f\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u062a\u0627\u06a9\u0646\u0648\u0646 \u0639\u0631\u0636\u0647 \u0631\u0633\u0645\u06cc \u0627\u0632 \u0633\u0648\u06cc \u0622\u0646 \u0634\u0631\u06a9\u062a \u0627\u0646\u062c\u0627\u0645 \u0646\u0634\u062f\u0647 \u0648 \u0627\u06a9\u0646\u0648\u0646 \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u0645\u0633\u06cc\u0631 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u0648\u0631\u0648\u062f \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%88%D8%B6%D8%B9%DB%8C%D8%AA_%D9%82%D8%A8%D9%84%DB%8C_%D8%B9%D8%B1%D8%B6%D9%87_%D8%A7%DB%8C%D9%86_%D9%85%D8%AD%D8%B5%D9%88%D9%84%D8%A7%D8%AA\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0648\u0636\u0639\u06cc\u062a \u0642\u0628\u0644\u06cc \u0639\u0631\u0636\u0647 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0634\u0631\u06a9\u062a<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0648\u0636\u0639\u06cc\u062a \u067e\u0631\u0648\u0698\u0647<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u06a9\u0631\u0645\u0627\u0646 \u0645\u0648\u062a\u0648\u0631<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u0628\u062f\u0648\u0646 \u0639\u0631\u0636\u0647 \u0631\u0633\u0645\u06cc<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u062f\u0631 \u0645\u0633\u06cc\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0627\u062e\u0630 \u0645\u062c\u0648\u0632<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B4%D8%AE%D8%B5%D8%A7%D8%AA_%D9%81%D9%86%DB%8C_%D8%AC%DB%8C%D9%84%DB%8C_%DA%AF%D9%84%DA%A9%D8%B3%DB%8C_L6_%D9%88_L7\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>6 \u0648 <\/strong><strong>L<\/strong><strong>7<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%82%D9%88%D8%A7%DB%8C_%D9%85%D8%AD%D8%B1%DA%A9%D9%87_%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86_%D9%87%DB%8C%D8%A8%D8%B1%DB%8C%D8%AF_%D8%A8%D8%A7_%D8%AA%D9%88%D8%A7%D9%86_%DB%B3%DB%B8%DB%B5_%D8%A7%D8%B3%D8%A8_%D8%A8%D8%AE%D8%A7%D8%B1\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0642\u0648\u0627\u06cc \u0645\u062d\u0631\u06a9\u0647 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f \u0628\u0627 \u062a\u0648\u0627\u0646 \u06f3\u06f8\u06f5 \u0627\u0633\u0628 \u0628\u062e\u0627\u0631<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u0647\u0631 \u062f\u0648 \u0645\u062f\u0644 L6 \u0648 L7 \u0627\u0632 \u0633\u06cc\u0633\u062a\u0645 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0627\u0632 \u06cc\u06a9 \u0645\u0648\u062a\u0648\u0631 \u06f1.\u06f5 \u0644\u06cc\u062a\u0631\u06cc \u062a\u0648\u0631\u0628\u0648\u0634\u0627\u0631\u0698 \u0628\u0646\u0632\u06cc\u0646\u06cc \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0645\u0648\u062a\u0648\u0631\u0647\u0627\u06cc \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc \u062a\u0634\u06a9\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u062e\u0631\u0648\u062c\u06cc \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u06cc\u0646 \u0633\u0627\u0645\u0627\u0646\u0647 \u0628\u0647 \u06f3\u06f8\u06f5 \u0627\u0633\u0628 \u0628\u062e\u0627\u0631 \u0642\u062f\u0631\u062a \u0648 \u06f5\u06f3\u06f5 \u0646\u06cc\u0648\u062a\u0646\u200c\u0645\u062a\u0631 \u06af\u0634\u062a\u0627\u0648\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0647\u0631 \u062f\u0648 \u062e\u0648\u062f\u0631\u0648 \u0627\u0639\u0644\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B4%D8%AE%D8%B5%D8%A7%D8%AA_%D9%BE%DB%8C%D8%B4%D8%B1%D8%A7%D9%86%D9%87\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0645\u0634\u062e\u0635\u0627\u062a \u067e\u06cc\u0634\u0631\u0627\u0646\u0647<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0645\u0634\u062e\u0635\u0647<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0645\u0642\u062f\u0627\u0631<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0646\u0648\u0639 \u0633\u06cc\u0633\u062a\u0645<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0645\u0648\u062a\u0648\u0631 \u0628\u0646\u0632\u06cc\u0646\u06cc<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f1.\u06f5 \u0644\u06cc\u062a\u0631\u06cc \u062a\u0648\u0631\u0628\u0648\u0634\u0627\u0631\u0698<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u0642\u062f\u0631\u062a \u062a\u0631\u06a9\u06cc\u0628\u06cc<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f3\u06f8\u06f5 \u0627\u0633\u0628 \u0628\u062e\u0627\u0631<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u06af\u0634\u062a\u0627\u0648\u0631 \u062a\u0631\u06a9\u06cc\u0628\u06cc<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f5\u06f3\u06f5 \u0646\u06cc\u0648\u062a\u0646\u200c\u0645\u062a\u0631<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B8%D8%B1%D9%81%DB%8C%D8%AA_%D8%A8%D8%A7%D8%AA%D8%B1%DB%8C_%D9%88_%D9%85%DB%8C%D8%B2%D8%A7%D9%86_%D9%BE%DB%8C%D9%85%D8%A7%DB%8C%D8%B4\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u062a\u0631\u06cc \u0648 \u0645\u06cc\u0632\u0627\u0646 \u067e\u06cc\u0645\u0627\u06cc\u0634<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u0627\u06cc\u0646 \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u062f\u0631 \u062f\u0648 \u062a\u06cc\u067e \u0645\u062e\u062a\u0644\u0641 \u0628\u0627 \u0628\u0627\u062a\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0639\u0631\u0636\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0646\u0633\u062e\u0647 \u062f\u0631\u0627\u06af\u0648\u0646 \u0628\u0647 \u0628\u0627\u062a\u0631\u06cc \u06f9.\u06f1 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a\u200c\u0633\u0627\u0639\u062a\u06cc \u0648 \u0646\u0633\u062e\u0647 \u062f\u0631\u0627\u06af\u0648\u0646 \u067e\u0644\u0627\u0633 \u0628\u0647 \u0628\u0627\u062a\u0631\u06cc \u06f1\u06f8.\u06f7 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a\u200c\u0633\u0627\u0639\u062a\u06cc \u0645\u062c\u0647\u0632 \u0627\u0633\u062a. \u0645\u06cc\u0632\u0627\u0646 \u067e\u06cc\u0645\u0627\u06cc\u0634 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0628\u0627 \u0628\u0627\u06a9 \u0633\u0648\u062e\u062a \u067e\u0631 \u0648 \u0634\u0627\u0631\u0698 \u06a9\u0627\u0645\u0644 \u0628\u0627\u062a\u0631\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u062f\u0648 \u062a\u06cc\u067e \u0628\u0647 \u062a\u0631\u062a\u06cc\u0628 \u06f1\u06f3\u06f1\u06f0 \u0648 \u06f1\u06f3\u06f7\u06f0 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631 \u0627\u0639\u0644\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%A8%D8%A7%D8%AA%D8%B1%DB%8C_%D9%88_%D8%A8%D8%B1%D8%AF_%D8%AD%D8%B1%DA%A9%D8%AA%DB%8C\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u0627\u062a\u0631\u06cc \u0648 \u0628\u0631\u062f \u062d\u0631\u06a9\u062a\u06cc<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062a\u06cc\u067e<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u062a\u0631\u06cc<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0628\u0631\u062f \u062a\u0631\u06a9\u06cc\u0628\u06cc<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062f\u0631\u0627\u06af\u0648\u0646<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f9.\u06f1 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a\u200c\u0633\u0627\u0639\u062a<\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f1\u06f3\u06f1\u06f0 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062f\u0631\u0627\u06af\u0648\u0646 \u067e\u0644\u0627\u0633<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f1\u06f8.\u06f7 \u06a9\u06cc\u0644\u0648\u0648\u0627\u062a\u200c\u0633\u0627\u0639\u062a<\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f1\u06f3\u06f7\u06f0 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%BE%DB%8C%D9%85%D8%A7%DB%8C%D8%B4_%D8%AA%D9%85%D8%A7%D9%85_%D8%A8%D8%B1%D9%82%DB%8C_%D9%88_%D8%B4%D8%AA%D8%A7%D8%A8_%D8%AE%D9%88%D8%AF%D8%B1%D9%88%D9%87%D8%A7\"><\/span><span style=\"font-size: 14pt;\"><strong>\u067e\u06cc\u0645\u0627\u06cc\u0634 \u062a\u0645\u0627\u0645 \u0628\u0631\u0642\u06cc \u0648 \u0634\u062a\u0627\u0628 \u062e\u0648\u062f\u0631\u0648\u0647\u0627<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u062f\u0631 \u062d\u0627\u0644\u062a \u062a\u0645\u0627\u0645 \u0627\u0644\u06a9\u062a\u0631\u06cc\u06a9\u06cc\u060c \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L7 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u0633\u062e\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u06cc\u0646 \u06f5\u06f5 \u062a\u0627 \u06f1\u06f1\u06f5 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631 \u062d\u0631\u06a9\u062a \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0639\u062f\u062f \u0628\u0631\u0627\u06cc \u0633\u062f\u0627\u0646 L6 \u0628\u06cc\u0646 \u06f6\u06f0 \u062a\u0627 \u06f1\u06f2\u06f5 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631 \u0627\u0639\u0644\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0634\u062a\u0627\u0628 \u0635\u0641\u0631 \u062a\u0627 \u0635\u062f L6 \u062d\u062f\u0648\u062f \u06f5.\u06f6 \u062b\u0627\u0646\u06cc\u0647 \u0648 \u0628\u0631\u0627\u06cc \u06a9\u0631\u0627\u0633\u200c\u0627\u0648\u0648\u0631 L7 \u0646\u0632\u062f\u06cc\u06a9 \u0628\u0647 \u06f6.\u06f9 \u062b\u0627\u0646\u06cc\u0647 \u0639\u0646\u0648\u0627\u0646 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D8%AD%D8%B1%DA%A9%D8%AA%DB%8C\"><\/span><span style=\"font-size: 14pt;\"><strong>\u0639\u0645\u0644\u06a9\u0631\u062f \u062d\u0631\u06a9\u062a\u06cc<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062e\u0648\u062f\u0631\u0648<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0628\u0631\u062f \u062a\u0645\u0627\u0645 \u0628\u0631\u0642\u06cc<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\"><strong>\u0634\u062a\u0627\u0628 \u0635\u0641\u0631 \u062a\u0627 \u0635\u062f<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>6<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f6\u06f0 \u062a\u0627 \u06f1\u06f2\u06f5 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631<\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f5.\u06f6 \u062b\u0627\u0646\u06cc\u0647<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-size: 14pt;\"><strong>\u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc <\/strong><strong>L<\/strong><strong>7<\/strong><\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f5\u06f5 \u062a\u0627 \u06f1\u06f1\u06f5 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631<\/span><\/td>\n<td><span style=\"font-size: 14pt;\">\u06f6.\u06f9 \u062b\u0627\u0646\u06cc\u0647<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u067e\u0633 \u0627\u0632 \u062a\u063a\u06cc\u06cc\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u062e\u0648\u062f\u060c \u0627\u06a9\u0646\u0648\u0646 \u0639\u0631\u0636\u0647 \u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 L7 \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0628\u062e\u0634\u06cc \u0627\u0632 \u0645\u062c\u0648\u0632\u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u0648\u0631\u0648\u062f \u0627\u06cc\u0646 \u062e\u0648\u062f\u0631\u0648\u0647\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u0634\u062f\u0647 \u0627\u0633\u062a. \u062f\u0648 \u0645\u062d\u0635\u0648\u0644 \u062c\u062f\u06cc\u062f \u062c\u06cc\u0644\u06cc \u0628\u0627 \u0641\u0646\u0627\u0648\u0631\u06cc \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f\u060c \u062a\u0648\u0627\u0646 \u0641\u0646\u06cc \u0628\u0627\u0644\u0627 \u0648 \u0628\u0631\u062f \u062d\u0631\u06a9\u062a\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u060c \u0627\u0632 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0628\u0627\u0632\u0627\u0631 \u062e\u0648\u062f\u0631\u0648\u0647\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062c\u06cc\u0644\u06cc \u06af\u0644\u06a9\u0633\u06cc L6 \u0648 L7 \u0628\u0627 \u0633\u0631\u0648\u0634 \u0645\u0628\u06cc\u0646\u0627 \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f. \u0627\u06cc\u0646 \u062f\u0648 \u0645\u062f\u0644 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0647\u06cc\u0628\u0631\u06cc\u062f \u0628\u0627 \u0642\u062f\u0631\u062a \u06f3\u06f8\u06f5 \u0627\u0633\u0628 \u0628\u062e\u0627\u0631 \u0648 \u0628\u0631\u062f \u062a\u0631\u06a9\u06cc\u0628\u06cc \u062a\u0627 \u06f1\u06f3\u06f7\u06f0 \u06a9\u06cc\u0644\u0648\u0645\u062a\u0631\u060c \u0645\u062c\u0648\u0632\u0647\u0627\u06cc \u0627\u0648\u0644\u06cc\u0647 \u0648\u0631\u0648\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n","protected":false},"author":1,"featured_media":23471,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-23470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-car-news"],"_links":{"self":[{"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/posts\/23470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/comments?post=23470"}],"version-history":[{"count":1,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/posts\/23470\/revisions"}],"predecessor-version":[{"id":23472,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/posts\/23470\/revisions\/23472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/media\/23471"}],"wp:attachment":[{"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/media?parent=23470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/categories?post=23470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wikishop.co\/mag\/wp-json\/wp\/v2\/tags?post=23470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}